{"id":6905,"date":"2018-08-22T14:03:32","date_gmt":"2018-08-22T17:03:32","guid":{"rendered":"http:\/\/www.rivera.gub.uy\/portal\/?p=6905"},"modified":"2018-08-22T14:03:40","modified_gmt":"2018-08-22T17:03:40","slug":"alumnos-de-4o-ano-de-la-escuela-no-1-artigas-visitaron-el-edificio-municipal","status":"publish","type":"post","link":"https:\/\/www.rivera.gub.uy\/portal\/alumnos-de-4o-ano-de-la-escuela-no-1-artigas-visitaron-el-edificio-municipal\/","title":{"rendered":"Alumnos de 4\u00ba a\u00f1o,  de la Escuela N\u00ba 1 Artigas, visitaron el edificio municipal"},"content":{"rendered":"<p>El Intendente Departamental, Dr. Marne Osorio Lima, tuvo el placer de recibir en su despacho, a una numerosa delegaci\u00f3n de alumnos del turno matutino de la Escuela N\u00ba1 de la ciudad de Rivera.<\/p>\n<p>Los ni\u00f1os le formularon diversas preguntas a Osorio, que iban desde como gobernar, hasta preguntas particulares como la t\u00edpica ?&#8230; so\u00f1abas ser intendente cuando eras chico..?.<!--more--><\/p>\n<p>Adem\u00e1s la Directora de la Escuela, junto a la sub Directora y docente, le plantearon al intendente, una problem\u00e1tica que corresponde al tema de la accesibilidad del edificio, teniendo en cuenta que dicha Escuela, integra la Red Mandela y por lo tanto recibe a ni\u00f1os con capacidades diferentes.<\/p>\n<p>Al final de la visita, Marne Osorio, les obsequi\u00f3 a los alumnos de 4\u00baA la bandera del departamento, una pelota de f\u00fatbol y una pelota de voleibol, generando la alegr\u00eda de los ni\u00f1os.<\/p>\n<div id='gallery-1' class='gallery galleryid-6905 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/asdfasdf.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/asdfasdf-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/asdfasdf-300x169.jpg 300w, https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/asdfasdf-150x84.jpg 150w, https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/asdfasdf-768x432.jpg 768w, https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/asdfasdf-1000x563.jpg 1000w, https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/asdfasdf-820x461.jpg 820w, https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/asdfasdf.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/escuela11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/escuela11-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/escuela11-300x169.jpg 300w, https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/escuela11-150x84.jpg 150w, https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/escuela11-768x432.jpg 768w, https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/escuela11-1000x563.jpg 1000w, https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/escuela11-820x461.jpg 820w, https:\/\/www.rivera.gub.uy\/portal\/wp-content\/uploads\/2018\/08\/escuela11.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>El Intendente Departamental, Dr. Marne Osorio Lima, tuvo el placer de recibir en su despacho, a una numerosa delegaci\u00f3n de alumnos del turno matutino de la Escuela N\u00ba1 de la ciudad de Rivera. Los ni\u00f1os le formularon diversas preguntas a Osorio, que iban desde como gobernar, hasta preguntas particulares como la t\u00edpica ?&#8230; so\u00f1abas ser [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[816,36,45,120,33],"class_list":["post-6905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades","tag-escuela-1","tag-intendencia","tag-intendente","tag-marne-osorio","tag-rivera"],"_links":{"self":[{"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/posts\/6905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/comments?post=6905"}],"version-history":[{"count":2,"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/posts\/6905\/revisions"}],"predecessor-version":[{"id":6909,"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/posts\/6905\/revisions\/6909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/media\/6907"}],"wp:attachment":[{"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/media?parent=6905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/categories?post=6905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rivera.gub.uy\/portal\/wp-json\/wp\/v2\/tags?post=6905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}